{"id":355,"count":1,"description":"","link":"https:\/\/sdahymnals.com\/Hymnal\/category\/author\/sara-f-adams\/","name":"Sara F. Adams","slug":"sara-f-adams","taxonomy":"category","parent":160,"meta":[],"_links":{"self":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/categories\/355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/categories\/160"}],"wp:post_type":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/posts?categories=355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}