{"id":172,"count":1,"description":"","link":"https:\/\/sdahymnals.com\/Hymnal\/category\/author\/arthur-c-ainger\/","name":"Arthur C. Ainger","slug":"arthur-c-ainger","taxonomy":"category","parent":160,"meta":[],"_links":{"self":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/categories\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/categories\/160"}],"wp:post_type":[{"href":"https:\/\/sdahymnals.com\/Hymnal\/wp-json\/wp\/v2\/posts?categories=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}